{"id":33,"date":"2024-01-05T00:45:01","date_gmt":"2024-01-05T00:45:01","guid":{"rendered":"https:\/\/atmpanama.org\/?page_id=33"},"modified":"2025-03-12T12:49:09","modified_gmt":"2025-03-12T17:49:09","slug":"documentos","status":"publish","type":"page","link":"https:\/\/atmpanama.org\/index.php\/documentos\/","title":{"rendered":"DOCUMENTOS"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"371\" src=\"https:\/\/atmpanama.org\/wp-content\/uploads\/2024\/01\/Captura-de-pantalla-2024-01-04-205026-1024x371.png\" alt=\"\" class=\"wp-image-64\" srcset=\"https:\/\/atmpanama.org\/wp-content\/uploads\/2024\/01\/Captura-de-pantalla-2024-01-04-205026-1024x371.png 1024w, https:\/\/atmpanama.org\/wp-content\/uploads\/2024\/01\/Captura-de-pantalla-2024-01-04-205026-300x109.png 300w, https:\/\/atmpanama.org\/wp-content\/uploads\/2024\/01\/Captura-de-pantalla-2024-01-04-205026-768x278.png 768w, https:\/\/atmpanama.org\/wp-content\/uploads\/2024\/01\/Captura-de-pantalla-2024-01-04-205026.png 1323w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Documentaci\u00f3n para inscripci\u00f3n de atletas en la plataforma de la ITTF<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este documento lo debe llenar el Atleta si es mayor de edad o por el padre o tutor del atleta si este es menor de edad.   Este formulario debe ser enviado a la ATMP mediante email.<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li><strong>Foto tipo carnet, de frente, sin reirse, en fondo blanco, sin sombrero o gorra. No puede ser selfie porque sale invertida.<\/strong><\/li>\n\n\n\n<li><strong>Direcci\u00f3n residencial completa.<\/strong><\/li>\n\n\n\n<li><strong>Foto del pasaporte vigente.<\/strong><\/li>\n\n\n\n<li><strong>Formulario ITTF lleno completo y firmado por el jugador, el entrenador y el padre o guardi\u00e1n si el jugador es menor de edad.<\/strong><\/li>\n\n\n\n<li><strong>Mandar todo en un solo email.<\/strong><\/li>\n\n\n\n<li><strong>Contactar al presidente o un miembro de la Junta Directiva para recibir el email donde deber\u00e1 enviar la informaci\u00f3n.<\/strong><\/li>\n<\/ol>\n\n\n\n<p class=\"wp-block-paragraph\">NOTA: Este procedimiento de <strong>Registro en la ITTF toma de 1 a 7 d\u00edas h\u00e1biles<\/strong> desde el momento que se env\u00eda a la ITTF.<\/p>\n\n\n\n<div data-wp-interactive=\"core\/file\" class=\"wp-block-file\"><object data-wp-bind--hidden=\"!state.hasPdfPreview\" hidden class=\"wp-block-file__embed\" data=\"https:\/\/atmpanama.org\/wp-content\/uploads\/2025\/03\/PAN-ITTF-Form-Registration.pdf\" type=\"application\/pdf\" style=\"width:100%;height:600px\" aria-label=\"Incrustado de PAN-ITTF Form Registration.\"><\/object><a id=\"wp-block-file--media-b9d8dde6-cfb5-495e-9183-0dd61aedede9\" href=\"https:\/\/atmpanama.org\/wp-content\/uploads\/2025\/03\/PAN-ITTF-Form-Registration.pdf\">PAN-ITTF Form Registration<\/a><a href=\"https:\/\/atmpanama.org\/wp-content\/uploads\/2025\/03\/PAN-ITTF-Form-Registration.pdf\" class=\"wp-block-file__button wp-element-button\" download aria-describedby=\"wp-block-file--media-b9d8dde6-cfb5-495e-9183-0dd61aedede9\">Descargar<\/a><\/div>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"font-style:normal;font-weight:900\">Reglamento Ranking<\/p>\n\n\n\n<div data-wp-interactive=\"core\/file\" class=\"wp-block-file\"><object data-wp-bind--hidden=\"!state.hasPdfPreview\" hidden class=\"wp-block-file__embed\" data=\"https:\/\/atmpanama.org\/wp-content\/uploads\/2024\/01\/Ranking-reglamento-01112019.pdf\" type=\"application\/pdf\" style=\"width:100%;height:600px\" aria-label=\"Incrustado de Ranking-reglamento-01112019.\"><\/object><a id=\"wp-block-file--media-1778ff34-df48-43a0-bc01-23bf5fad001a\" href=\"https:\/\/atmpanama.org\/wp-content\/uploads\/2024\/01\/Ranking-reglamento-01112019.pdf\">Ranking-reglamento-01112019<\/a><a href=\"https:\/\/atmpanama.org\/wp-content\/uploads\/2024\/01\/Ranking-reglamento-01112019.pdf\" class=\"wp-block-file__button wp-element-button\" download aria-describedby=\"wp-block-file--media-1778ff34-df48-43a0-bc01-23bf5fad001a\">Descargar<\/a><\/div>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"font-style:normal;font-weight:900\">Resultados<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Estatutos de la Asociacion de Tenis de Mesa de Panama ATMP<\/strong> <\/p>\n\n\n\n<div data-wp-interactive=\"core\/file\" class=\"wp-block-file\"><object data-wp-bind--hidden=\"!state.hasPdfPreview\" hidden class=\"wp-block-file__embed\" data=\"https:\/\/atmpanama.org\/wp-content\/uploads\/2024\/04\/Estatutos-ATMP-Junio2017-.pdf\" type=\"application\/pdf\" style=\"width:100%;height:600px\" aria-label=\"Incrustado de Estatutos-ATMP-Junio2017-.\"><\/object><a id=\"wp-block-file--media-ff0680aa-b528-455c-9530-74a68104fb15\" href=\"https:\/\/atmpanama.org\/wp-content\/uploads\/2024\/04\/Estatutos-ATMP-Junio2017-.pdf\">Estatutos-ATMP-Junio2017-<\/a><a href=\"https:\/\/atmpanama.org\/wp-content\/uploads\/2024\/04\/Estatutos-ATMP-Junio2017-.pdf\" class=\"wp-block-file__button wp-element-button\" download aria-describedby=\"wp-block-file--media-ff0680aa-b528-455c-9530-74a68104fb15\">Descargar<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Documentaci\u00f3n para inscripci\u00f3n de atletas en la plataforma de la ITTF Este documento lo debe llenar el Atleta si es mayor de edad o por el padre o tutor del atleta si este es menor de edad. Este formulario debe ser enviado a la ATMP mediante email. NOTA: Este procedimiento de Registro en la ITTF [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":3,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-33","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/atmpanama.org\/index.php\/wp-json\/wp\/v2\/pages\/33","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/atmpanama.org\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/atmpanama.org\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/atmpanama.org\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/atmpanama.org\/index.php\/wp-json\/wp\/v2\/comments?post=33"}],"version-history":[{"count":9,"href":"https:\/\/atmpanama.org\/index.php\/wp-json\/wp\/v2\/pages\/33\/revisions"}],"predecessor-version":[{"id":808,"href":"https:\/\/atmpanama.org\/index.php\/wp-json\/wp\/v2\/pages\/33\/revisions\/808"}],"wp:attachment":[{"href":"https:\/\/atmpanama.org\/index.php\/wp-json\/wp\/v2\/media?parent=33"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}